{"id":5576,"date":"2026-02-08T22:36:59","date_gmt":"2026-02-08T21:36:59","guid":{"rendered":"https:\/\/eschringen.de\/wordpress\/?post_type=tribe_events&#038;p=5576"},"modified":"2026-04-19T19:24:55","modified_gmt":"2026-04-19T17:24:55","slug":"dorfgemeinschaftsfest-4","status":"publish","type":"tribe_events","link":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/","title":{"rendered":"Dorfgemeinschaftsfest"},"content":{"rendered":"<p><strong>Dorfgemeinschaftsfest am 14. Mai 2026<\/strong><\/p>\n<p>Einer der sch\u00f6nsten Dorfpl\u00e4tze des Saarlandes liegt bekanntlich in Eschringen. Genau dort startet am 14. Mai wieder das Dorfgemeinschaftsfest &#8211; sozusagen eine Ko-Produktion der Arbeitsgemeinschaft der Eschringer Vereine. NABU, Musikverein Lyra, Feuerwehr und TuS gestalten das Fest gemeinsam mit vielen freiwilligen Helfern.<br \/>\nUm elf Uhr geht\u2019s los, dann macht sich die Lyra bereit f\u00fcr den musikalischen Fr\u00fchschoppen. Dazu gibt\u2019s nat\u00fcrlich Getr\u00e4nke zum Ansto\u00dfen. Auch das kulinarische Angebot kommt dann ins Laufen: sp\u00e4testens um 12 Uhr wird der Spie\u00dfbraten mit Sp\u00e4tzlen serviert und am Grillstand k\u00fcmmern sich mehrere Teams um W\u00fcrstchen und Pommes. Und nat\u00fcrlich ist auch wieder ein Kuchenstand mit am Start, der hoffentlich von vielen freiwilligen B\u00e4ckerinnen und B\u00e4ckern ordentlich best\u00fcckt wird. Da warten wir noch auf entsprechende s\u00fc\u00dfe Spenden. (siehe unten!) Kaffee gibt\u2019s nat\u00fcrlich auch. Ab 17 Uhr werden dann wieder Flammkuchen gebacken \u2013 in einer traditionellen und einer vegetarischen Variante. Bei der Auswahl sollte eigentlich niemand hungrig nachhause gehen m\u00fcssen.<br \/>\nDer Verkauf l\u00e4uft wieder \u00fcber Bons, die man an der zentralen Kasse auf dem Festgel\u00e4nde kaufen kann.<br \/>\nAber wie immer geht\u2019s nicht nur um Essen und Trinken, sondern auch um viel Unterhaltung. F\u00fcr die kleinen G\u00e4ste gibt es ab 14 Uhr wieder Kinderschminken und ein Mal-Angebot. Und musikalisch sorgt ab 15 Uhr die Band Happy Music f\u00fcr Stimmung.<br \/>\nVor allem geht\u2019s aber nat\u00fcrlich darum, dass alle mal wieder zusammenkommen und gemeinsam feiern. Insofern hoffen wir jetzt, dass sich der Mai von seiner freundlichen Seite zeigt und am Vatertag f\u00fcr ordentlich Sonnenschein sorgt.<br \/>\nWer spontan noch Lust hat, beim Dorfgemeinschaftsfest zu helfen, bitte meldet euch bei Stefan Vogelgesang: Tel. 06893\/6553 (auch WhatsApp) oder per Mail info@eschringen.de.<br \/>\nUnd auch \u00fcber Kuchenspenden w\u00fcrden wir uns riesig freuen!! W\u00e4re toll, wenn wir wieder so eine gro\u00dfartige Auswahl h\u00e4tten, wie beim letzten Fest. Gerne im Vorfeld bei mir melden: Simone Bla\u00df 0160\/7911495 (auch WhatsApp) oder per mail: simoneblass@t-online.de Dann wissen wir schonmal, womit wir planen k\u00f6nnen. Wir sind am 14.5. ab 12 Uhr vor Ort und nehmen alle Kuchen entgegen und k\u00f6nnen sie auch k\u00fchlen, wenn notwendig.<br \/>\nWir freuen uns auf ein richtig sch\u00f6nes Fest mit euch allen!<\/p>\n<p>Ein Dank vorab an die <a href=\"https:\/\/www.sparkasse-saarbruecken.de\">Sparkasse Saarbr\u00fccken<\/a>, die unser Fest unterst\u00fctzt.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5672 size-full\" src=\"https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=1200%2C1697&#038;ssl=1\" alt=\"\" width=\"1200\" height=\"1697\" srcset=\"https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?w=1810&amp;ssl=1 1810w, https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=212%2C300&amp;ssl=1 212w, https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=724%2C1024&amp;ssl=1 724w, https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=768%2C1086&amp;ssl=1 768w, https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=1086%2C1536&amp;ssl=1 1086w, https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2026\/04\/Plakat_DGF_neu-scaled.jpg?resize=1448%2C2048&amp;ssl=1 1448w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dorfgemeinschaftsfest am 14. Mai 2026 Einer der sch\u00f6nsten Dorfpl\u00e4tze des Saarlandes liegt bekanntlich in Eschringen. Genau dort startet am 14. Mai wieder das Dorfgemeinschaftsfest &#8211; sozusagen eine Ko-Produktion der Arbeitsgemeinschaft der Eschringer Vereine. NABU, Musikverein Lyra, Feuerwehr und TuS gestalten das Fest gemeinsam mit vielen freiwilligen Helfern. Um elf Uhr geht\u2019s los, dann macht sich &#8230; <a title=\"Dorfgemeinschaftsfest\" class=\"read-more\" href=\"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/\" aria-label=\"Mehr Informationen \u00fcber Dorfgemeinschaftsfest\">Weiterlesen &#8230;<\/a><\/p>\n","protected":false},"author":1,"featured_media":1428,"template":"","meta":{"ngg_post_thumbnail":0,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5576","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dorfgemeinschaftsfest - Eschringen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dorfgemeinschaftsfest - Eschringen\" \/>\n<meta property=\"og:description\" content=\"Dorfgemeinschaftsfest am 14. Mai 2026 Einer der sch\u00f6nsten Dorfpl\u00e4tze des Saarlandes liegt bekanntlich in Eschringen. Genau dort startet am 14. Mai wieder das Dorfgemeinschaftsfest &#8211; sozusagen eine Ko-Produktion der Arbeitsgemeinschaft der Eschringer Vereine. NABU, Musikverein Lyra, Feuerwehr und TuS gestalten das Fest gemeinsam mit vielen freiwilligen Helfern. Um elf Uhr geht\u2019s los, dann macht sich ... Weiterlesen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Eschringen\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-19T17:24:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/06\/AG_kal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"210\" \/>\n\t<meta property=\"og:image:height\" content=\"212\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/\",\"url\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/\",\"name\":\"Dorfgemeinschaftsfest - Eschringen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/AG_kal.jpg?fit=210%2C212&ssl=1\",\"datePublished\":\"2026-02-08T21:36:59+00:00\",\"dateModified\":\"2026-04-19T17:24:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/AG_kal.jpg?fit=210%2C212&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/AG_kal.jpg?fit=210%2C212&ssl=1\",\"width\":210,\"height\":212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/event\\\/dorfgemeinschaftsfest-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dorfgemeinschaftsfest\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/\",\"name\":\"Eschringen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#organization\",\"name\":\"Eschringen\",\"url\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/2017_kw15.jpg\",\"contentUrl\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/2017_kw15.jpg\",\"width\":784,\"height\":447,\"caption\":\"Eschringen\"},\"image\":{\"@id\":\"https:\\\/\\\/eschringen.de\\\/wordpress\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dorfgemeinschaftsfest - Eschringen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/","og_locale":"de_DE","og_type":"article","og_title":"Dorfgemeinschaftsfest - Eschringen","og_description":"Dorfgemeinschaftsfest am 14. Mai 2026 Einer der sch\u00f6nsten Dorfpl\u00e4tze des Saarlandes liegt bekanntlich in Eschringen. Genau dort startet am 14. Mai wieder das Dorfgemeinschaftsfest &#8211; sozusagen eine Ko-Produktion der Arbeitsgemeinschaft der Eschringer Vereine. NABU, Musikverein Lyra, Feuerwehr und TuS gestalten das Fest gemeinsam mit vielen freiwilligen Helfern. Um elf Uhr geht\u2019s los, dann macht sich ... Weiterlesen ...","og_url":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/","og_site_name":"Eschringen","article_modified_time":"2026-04-19T17:24:55+00:00","og_image":[{"width":210,"height":212,"url":"https:\/\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/06\/AG_kal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/","url":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/","name":"Dorfgemeinschaftsfest - Eschringen","isPartOf":{"@id":"https:\/\/eschringen.de\/wordpress\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/#primaryimage"},"image":{"@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/06\/AG_kal.jpg?fit=210%2C212&ssl=1","datePublished":"2026-02-08T21:36:59+00:00","dateModified":"2026-04-19T17:24:55+00:00","breadcrumb":{"@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/#primaryimage","url":"https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/06\/AG_kal.jpg?fit=210%2C212&ssl=1","contentUrl":"https:\/\/i0.wp.com\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/06\/AG_kal.jpg?fit=210%2C212&ssl=1","width":210,"height":212},{"@type":"BreadcrumbList","@id":"https:\/\/eschringen.de\/wordpress\/event\/dorfgemeinschaftsfest-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/eschringen.de\/wordpress\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/eschringen.de\/wordpress\/events\/"},{"@type":"ListItem","position":3,"name":"Dorfgemeinschaftsfest"}]},{"@type":"WebSite","@id":"https:\/\/eschringen.de\/wordpress\/#website","url":"https:\/\/eschringen.de\/wordpress\/","name":"Eschringen","description":"","publisher":{"@id":"https:\/\/eschringen.de\/wordpress\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eschringen.de\/wordpress\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/eschringen.de\/wordpress\/#organization","name":"Eschringen","url":"https:\/\/eschringen.de\/wordpress\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/eschringen.de\/wordpress\/#\/schema\/logo\/image\/","url":"https:\/\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/03\/2017_kw15.jpg","contentUrl":"https:\/\/eschringen.de\/wordpress\/wp-content\/uploads\/2017\/03\/2017_kw15.jpg","width":784,"height":447,"caption":"Eschringen"},"image":{"@id":"https:\/\/eschringen.de\/wordpress\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/5576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":11,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/5576\/revisions"}],"predecessor-version":[{"id":5685,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events\/5576\/revisions\/5685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/media\/1428"}],"wp:attachment":[{"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/media?parent=5576"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tags?post=5576"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/eschringen.de\/wordpress\/wp-json\/wp\/v2\/tribe_events_cat?post=5576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}